{"id":4418,"date":"2025-09-04T15:40:08","date_gmt":"2025-09-04T13:40:08","guid":{"rendered":"https:\/\/www2.cms.hu-berlin.de\/queer-reading\/?p=4418"},"modified":"2025-09-04T15:41:46","modified_gmt":"2025-09-04T13:41:46","slug":"brecht-bertolt-im-dickicht-der-staedte-7","status":"publish","type":"post","link":"https:\/\/www2.cms.hu-berlin.de\/queer-reading\/brecht-bertolt-im-dickicht-der-staedte-7\/","title":{"rendered":"Sacher-Masoch, Marfa von: &#8222;W\u00fcrde zu geben den Verschm\u00e4hten&#8230;&#8220;"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4418\" class=\"elementor elementor-4418\">\n\t\t\t\t<div class=\"elementor-element elementor-element-74959c31 e-flex e-con-boxed e-con e-parent\" data-id=\"74959c31\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7853969 ob-has-background-overlay elementor-widget elementor-widget-tp-smooth-scroll\" data-id=\"7853969\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;}\" data-widget_type=\"tp-smooth-scroll.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"plus-smooth-scroll\" data-scroll-type=\"basic\" data-frameRate=\"144\" data-animationTime=\"1100\" data-stepSize=\"157\" data-pulseAlgorithm=\"1\" data-pulseScale=\"4\" data-pulseNormalize=\"1\" data-accelerationDelta=\"50\" data-accelerationMax=\"3\" data-keyboardSupport=\"1\" data-arrowScroll=\"50\" data-touchpadSupport=\"0\" data-fixedBackground=\"1\" data-basicdata=\"{&quot;Browsers&quot;:[&quot;ieWin7&quot;,&quot;chrome&quot;,&quot;firefox&quot;,&quot;safari&quot;]}\"   data-tablet-off=&quot;no&quot; ><script>var smoothAllowedBrowsers = [\"ieWin7\",\"chrome\",\"firefox\",\"safari\"]<\/script><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77396924 ob-harakiri-inherit ob-has-background-overlay elementor-widget elementor-widget-heading\" data-id=\"77396924\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_harakiri_text_clip&quot;:&quot;none&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Sacher-Masoch, Marfa von: \"W\u00fcrde zu geben den Verschm\u00e4hten...\" (1917)<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-17ed77be e-flex e-con-boxed e-con e-parent\" data-id=\"17ed77be\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-54bc64ad ob-harakiri-inherit ob-has-background-overlay elementor-widget elementor-widget-heading\" data-id=\"54bc64ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_harakiri_text_clip&quot;:&quot;none&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Stammdaten<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-162cb20a e-flex e-con-boxed e-con e-parent\" data-id=\"162cb20a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5394f6a6 e-flex e-con-boxed e-con e-child\" data-id=\"5394f6a6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-73bbf7d e-grid e-con-boxed e-con e-child\" data-id=\"73bbf7d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-56104b8e animated-slow ob-harakiri-inherit elementor-invisible ob-has-background-overlay elementor-widget elementor-widget-text-editor\" data-id=\"56104b8e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Autor*in<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b6db878 animated-slow ob-harakiri-inherit elementor-invisible ob-has-background-overlay elementor-widget elementor-widget-text-editor\" data-id=\"2b6db878\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Marfa von Sacher-Masoch (vrh. Saternus)<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-15cc0f41 e-flex e-con-boxed e-con e-child\" data-id=\"15cc0f41\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9933b59 e-grid e-con-boxed e-con e-child\" data-id=\"9933b59\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-19528347 animated-slow ob-harakiri-inherit elementor-invisible ob-has-background-overlay elementor-widget elementor-widget-text-editor\" data-id=\"19528347\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Vollst\u00e4ndiger Titel<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-738c613e animated-slow ob-harakiri-inherit elementor-invisible ob-has-background-overlay elementor-widget elementor-widget-text-editor\" data-id=\"738c613e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><em>\u201eW\u00fcrde zu geben den Verschm\u00e4hten\u2026\u201c<\/em><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-670c5d3e e-flex e-con-boxed e-con e-child\" data-id=\"670c5d3e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-33d7c71e e-grid e-con-boxed e-con e-child\" data-id=\"33d7c71e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7f281deb animated-slow ob-harakiri-inherit elementor-invisible ob-has-background-overlay elementor-widget elementor-widget-text-editor\" data-id=\"7f281deb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Pseudonym<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-34529da8 animated-slow ob-harakiri-inherit elementor-invisible ob-has-background-overlay elementor-widget elementor-widget-text-editor\" data-id=\"34529da8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>M. Coray<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-715006dd e-flex e-con-boxed e-con e-child\" data-id=\"715006dd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5390a316 e-grid e-con-boxed e-con e-child\" data-id=\"5390a316\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6145c3c5 animated-slow ob-harakiri-inherit elementor-invisible ob-has-background-overlay elementor-widget elementor-widget-text-editor\" data-id=\"6145c3c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ersterscheinungsjahr<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c6c2095 animated-slow ob-harakiri-inherit elementor-invisible ob-has-background-overlay elementor-widget elementor-widget-text-editor\" data-id=\"5c6c2095\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>1917 (dritte und vierte Auflage im Jahr 1925)<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-75139550 e-flex e-con-boxed e-con e-child\" data-id=\"75139550\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6966f1ac e-grid e-con-boxed e-con e-child\" data-id=\"6966f1ac\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-228b5435 animated-slow ob-harakiri-inherit elementor-invisible ob-has-background-overlay elementor-widget elementor-widget-text-editor\" data-id=\"228b5435\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Epoche<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-796ea983 animated-slow ob-harakiri-inherit elementor-invisible ob-has-background-overlay elementor-widget elementor-widget-text-editor\" data-id=\"796ea983\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Deutsches Kaiserreich<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-660166f6 e-flex e-con-boxed e-con e-child\" data-id=\"660166f6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-40d6011c e-grid e-con-boxed e-con e-child\" data-id=\"40d6011c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-85383e9 animated-slow ob-harakiri-inherit elementor-invisible ob-has-background-overlay elementor-widget elementor-widget-text-editor\" data-id=\"85383e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Fassung \u00a7175<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ca94baa animated-slow ob-harakiri-inherit elementor-invisible ob-has-background-overlay elementor-widget elementor-widget-text-editor\" data-id=\"1ca94baa\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>1872-1935<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4c6d8af0 e-flex e-con-boxed e-con e-child\" data-id=\"4c6d8af0\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5483ebec e-grid e-con-boxed e-con e-child\" data-id=\"5483ebec\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-248499ae animated-slow ob-harakiri-inherit elementor-invisible ob-has-background-overlay elementor-widget elementor-widget-text-editor\" data-id=\"248499ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Gattung<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-71df7cd4 animated-slow ob-harakiri-inherit elementor-invisible ob-has-background-overlay elementor-widget elementor-widget-text-editor\" data-id=\"71df7cd4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Roman<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2233a157 e-flex e-con-boxed e-con e-parent\" data-id=\"2233a157\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3d30d296 ob-harakiri-inherit ob-has-background-overlay elementor-widget elementor-widget-heading\" data-id=\"3d30d296\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_harakiri_text_clip&quot;:&quot;none&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Biografisches<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-513af1d e-flex e-con-boxed e-con e-parent\" data-id=\"513af1d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3d463b2e e-con-full e-flex e-con e-child\" data-id=\"3d463b2e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bc5a3d3 elementor-widget__width-initial ob-has-background-overlay elementor-widget elementor-widget-image\" data-id=\"bc5a3d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_photomorph_use&quot;:&quot;no&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"308\" height=\"419\" src=\"https:\/\/www2.cms.hu-berlin.de\/queer-reading\/wp-content\/uploads\/2025\/08\/wuerde-zu-geben-deckblatt.png\" class=\"attachment-large size-large wp-image-4419\" alt=\"\" srcset=\"https:\/\/www2.cms.hu-berlin.de\/queer-reading\/wp-content\/uploads\/2025\/08\/wuerde-zu-geben-deckblatt.png 308w, https:\/\/www2.cms.hu-berlin.de\/queer-reading\/wp-content\/uploads\/2025\/08\/wuerde-zu-geben-deckblatt-221x300.png 221w\" sizes=\"(max-width: 308px) 100vw, 308px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b272ae4 animated-slow ob-harakiri-inherit elementor-invisible ob-has-background-overlay elementor-widget elementor-widget-text-editor\" data-id=\"b272ae4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Abb 1. Deckblatt der Erstausgabe des Romans von 1917.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4be4e0bf e-con-full e-flex e-con e-child\" data-id=\"4be4e0bf\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-621ba44 animated-slow elementor-widget-laptop__width-initial ob-harakiri-inherit elementor-invisible ob-has-background-overlay elementor-widget elementor-widget-text-editor\" data-id=\"621ba44\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Marfa von Sacher-Masoch (geboren am 8. Juni 1887 in Paris, gestorben am 7. Februar 1963 in Freiburg, verheiratete Saternus, Pseudonym M. Coray) war Tochter des Schriftstellers Leopold von Sacher-Masoch (1836-1895) und seiner zweiten Ehefrau Hulda Meister (1846-1918). Den Gro\u00dfteil ihrer Jugend verbrachte sie in einem Landhaus in Lindheim (Hessen), einige Jahre auch in M\u00fcnchen. Ihre erste, im Jahr 1904 ver\u00f6ffentlichte Novelle <em>Die Grottenfee<\/em> verfasste sie im Alter von dreizehn Jahren. Ihr Werk umfasst \u00fcber vierzig Romane sowie etliche Feuilletonartikel und kleinere Arbeiten. 1913 lernte sie w\u00e4hrend ihrer Arbeit in der Presseagentur Dammert in Berlin den Journalisten Arthur Saternus kennen, den sie 1919 heiratete. Von 1934 bis 1948 lebte das Paar mit der gemeinsamen Tochter Mechthild (1920-2015) in Ungarn. Marfa von Sacher-Masochs Buchverk\u00e4ufe sicherten der Familie zeitweise die finanzielle Existenz. Nach 1948 lebte das Paar in M\u00fcnchen, K\u00f6ln und Freiburg im Breisgau, wo Marfa von Sacher-Masoch\/Saternus 1963 starb.<\/p><p>Im Gegensatz zu ihrem ber\u00fchmten Vater, auf dessen Namen der Terminus \u201aMasochismus\u2018 zur\u00fcckgeht, ist Marfa von Sacher-Masoch heute weitestgehend in Vergessenheit geraten. Keiner ihrer Romane wurde nach ihrem Tod neu aufgelegt. Erst 2022 erschien eine Edition ihrer bislang unver\u00f6ffentlichten Kindheitserinnerungen <em>Die drei Kinder im Herrengarten<\/em>, die auch einen von ihrer Tochter Mechthild Saternus verfassten biografischen Bericht enth\u00e4lt.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7b342ae2 e-flex e-con-boxed e-con e-parent\" data-id=\"7b342ae2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-57938dc9 text-left ob-has-background-overlay elementor-widget elementor-widget-tp-blockquote\" data-id=\"57938dc9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;}\" data-widget_type=\"tp-blockquote.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pt-plus-text-block-wrapper\" ><div class=\"text_block_parallax\"><div class=\"plus_blockquote quote-style-2   none \" ><blockquote class=\"quote-text\"><span class=\"tp-bq-desc\"><p>\u201eDein Hund wird bei der n\u00e4chsten Neugeburt Staatsanwalt \u2013 nein, und was der f\u00fcr eine Wut auf den \u00a7 175 haben wird! Eine Wut, sage ich Dir!\u201c<\/p><\/span><p class=\"quote_author\">(Sacher-Masoch, 1917, S. 302)<\/p><\/blockquote><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7dd08279 e-flex e-con-boxed e-con e-parent\" data-id=\"7dd08279\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-64e8dd28 ob-harakiri-inherit ob-has-background-overlay elementor-widget elementor-widget-heading\" data-id=\"64e8dd28\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_harakiri_text_clip&quot;:&quot;none&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Inhalt<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f23c84b animated-slow ob-harakiri-inherit elementor-invisible ob-has-background-overlay elementor-widget elementor-widget-text-editor\" data-id=\"5f23c84b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Zuf\u00e4llig lernen sich der junge Operns\u00e4nger Le\u00f3n Withalm und die wenige Jahre \u00e4ltere \u00c4rztin Dr. Barbara Rabitow kennen und empfinden bald Sympathie f\u00fcreinander. Barbara ist willensstark, unabh\u00e4ngig und geht ganz in ihrem Beruf auf. Sie genie\u00dft auch unter den m\u00e4nnlichen Berufskollegen hohes Ansehen. Le\u00f3n ist ein sensibler K\u00fcnstler, der am Beginn einer vielversprechenden Opernkarriere als Baritons\u00e4nger steht. Beide verkehren in den gehobenen Kreisen einer ungenannten deutschen Stadt; neben privaten Besuchen trifft man sich in der Oper, bei Ateliersempf\u00e4ngen und auf Maskenb\u00e4llen.<\/p><p>Als sich Ger\u00fcchte \u00fcber Le\u00f3ns Homosexualit\u00e4t verbreiten, wird dieser zunehmend sozial isoliert. Bald ist Barbara die einzige Person, die noch uneingeschr\u00e4nkt zu ihm steht \u2013 auch als Le\u00f3n ihr offenbart, dass er tats\u00e4chlich \u201ekontr\u00e4r\u201c (S. 179) empfindet. Versch\u00e4rft wird Le\u00f3ns \u00c4chtung, als er einen alten Bekannten bei sich aufnimmt: Viktor Soyka, der f\u00fcnf Jahre wegen Verst\u00f6\u00dfen gegen den \u00a7 175 im Zuchthaus verb\u00fc\u00dfen musste. Viktor ist verzweifelt und sieht f\u00fcr sich keine Zukunft. Auch die enge Freundschaft zu Le\u00f3n und Barbara kann ihn letztlich nicht davon abhalten, sich das Leben zu nehmen.\u00a0<\/p><p>Le\u00f3ns und Barbaras Verh\u00e4ltnis intensiviert sich weiter. Nachdem Barbara in einer Laienauff\u00fchrung der Nibelungen die Rolle des Dietrich von Bern \u00fcbernimmt und sich Le\u00f3n zuhause in ihrem M\u00e4nnerkost\u00fcm zeigt, dr\u00e4ngt er ihr einen Kuss auf, wogegen sie sich jedoch wehrt. Besch\u00e4mt fl\u00fcchtet Le\u00f3n nach Hause. Als er gerade im Begriff ist, sich mit einer Pistole zu erschie\u00dfen, steht Barbara vor der T\u00fcr. Im folgenden Gespr\u00e4ch vers\u00f6hnen sich die beiden nicht nur, sondern sie verloben sich. Le\u00f3n gesteht ihr seine Liebe und hofft, durch Barbara seine Homosexualit\u00e4t zu \u00fcberwinden: \u201e[W]enn Du dich mir frei hingibst, dann weicht aller b\u00f6ser Zauber von mir, du wirst ihn vertreiben!\u201c (S. 381). Barbara wiederum ist bereit, f\u00fcr Le\u00f3n ihre Autonomie aufzugeben und ihre sexuelle Aversion zu \u00fcberwinden. Die Verlobung sorgt im Bekanntenkreis f\u00fcr Irritation, rehabilitiert aber Le\u00f3ns gesch\u00e4digten Ruf. Bis zur Hochzeit ist das Paar verunsichert, ob der Plan aufgehen kann; in der Hochzeitsnacht \u201eweck[t]\u201c (S. 413) Le\u00f3n dann tats\u00e4chlich Barbaras sexuelles Begehren und glaubt sich selbst \u201efrei\u201c (ebd.) von seiner Homosexualit\u00e4t.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-79a5bad7 e-flex e-con-boxed e-con e-parent\" data-id=\"79a5bad7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-11e103a2 ob-harakiri-inherit ob-has-background-overlay elementor-widget elementor-widget-heading\" data-id=\"11e103a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_harakiri_text_clip&quot;:&quot;none&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Themen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e621a9c animated-slow ob-harakiri-inherit elementor-invisible ob-has-background-overlay elementor-widget elementor-widget-text-editor\" data-id=\"5e621a9c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Scharfe Kritik am \u00a7 175<\/li><li>Mechanismen sozialer Ausgrenzung<\/li><li>Verarbeitung sexualwissenschaftlicher, psychoanalytischer und feministischer Diskurse<\/li><li>Beziehung zwischen femininem Mann und maskuliner Frau \/ \u201aErl\u00f6sung\u2018 des homosexuellen Mannes<\/li><li>Verbindung von Ehe und Freundschaft<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-22beb57 e-flex e-con-boxed e-con e-parent\" data-id=\"22beb57\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0f9b11e ob-has-background-overlay elementor-widget elementor-widget-image\" data-id=\"0f9b11e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_photomorph_use&quot;:&quot;no&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"691\" src=\"https:\/\/www2.cms.hu-berlin.de\/queer-reading\/wp-content\/uploads\/2025\/08\/00000018.tif.original-1024x691.jpg\" class=\"attachment-large size-large wp-image-4439\" alt=\"\" srcset=\"https:\/\/www2.cms.hu-berlin.de\/queer-reading\/wp-content\/uploads\/2025\/08\/00000018.tif.original-1024x691.jpg 1024w, https:\/\/www2.cms.hu-berlin.de\/queer-reading\/wp-content\/uploads\/2025\/08\/00000018.tif.original-300x202.jpg 300w, https:\/\/www2.cms.hu-berlin.de\/queer-reading\/wp-content\/uploads\/2025\/08\/00000018.tif.original-768x518.jpg 768w, https:\/\/www2.cms.hu-berlin.de\/queer-reading\/wp-content\/uploads\/2025\/08\/00000018.tif.original-1536x1037.jpg 1536w, https:\/\/www2.cms.hu-berlin.de\/queer-reading\/wp-content\/uploads\/2025\/08\/00000018.tif.original-2048x1382.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df23f8e animated-slow ob-harakiri-inherit elementor-invisible ob-has-background-overlay elementor-widget elementor-widget-text-editor\" data-id=\"df23f8e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Abb 2. Werbeanzeige des Dr. Sally Rabinowitz Verlag f\u00fcr <em>\u201eW\u00fcrde zu geben den Verschm\u00e4hten\u2026<\/em>\u201c. In: B\u00f6rsenblatt f\u00fcr den deutschen Buchhandel, Ausgabe vom 12.09.1917. Digitalisat der SLUB Dresden. [<a href=\"http:\/\/digital.slub-dresden.de\/id39946221X-19170912\/18\">Link zum Digitalisat<\/a>]<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-306d5b07 e-flex e-con-boxed e-con e-parent\" data-id=\"306d5b07\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1762ced6 ob-harakiri-inherit ob-has-background-overlay elementor-widget elementor-widget-heading\" data-id=\"1762ced6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_harakiri_text_clip&quot;:&quot;none&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Motive<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-219bea86 ob-has-background-overlay elementor-widget elementor-widget-tp-accordion\" data-id=\"219bea86\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;}\" data-widget_type=\"tp-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"theplus-accordion-wrapper elementor-accordion   \"\n    id=\"accordion6a0425f95b30d\" data-accordion-id=\"accordion6a0425f95b30d\"\n    data-connection=\"\"\n    data-accordion-type=\"accordion\"\n    data-heightlight-text       role=\"tablist\" >\n\n            <div class=\"theplus-accordion-item\"  role=\"tab\">\n            <div id=\"elementor-tab-title-5631\" class=\"elementor-tab-title plus-accordion-header 0 text-left \" data-tab=\"1\" aria-controls=\"elementor-tab-content-5631\">\n                                \n                <span style=\"width:100%\">Kritik am \u00a7 175<\/span>                <span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-angle-down\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-angle-up\"><\/i><\/span>            <\/div>\n\n                        <div id=\"elementor-tab-content-5631\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content 0 \" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-5631\">\n                <div class=\"plus-content-editor\" ><ul><li>\u201eAber k\u00f6nnen Sie f\u00fchlen, was das f\u00fcr ihn hie\u00df? Oskar Wilde zu Zelle 33 werden? Vielleicht heben Sie die Achseln und sagen, wie kann ein solcher Mensch sich so verlieren, er wei\u00df was darauf steht, warum tut er es? Aber da sage ich von Gottes- und Menschengesetz wegen: kann ein Gef\u00fchl bestraft werden?\u201c (S. 254)<\/li><li>\u201e\u201aEr war ja zuletzt mein Sch\u00fcler,\u2018 wandte sich Soyka an Dr. Rabitow, \u201aallerdings nur kurze Zeit, dann wurde ich als antisoziales Individuum eingesteckt!\u2018\u201c (S. 267)<\/li><li><p>\u201eWas geht mein Sexus den Staat an? Gef\u00e4hrdet er ihn? Bedroht er ihn? [\u2026] [B]in ich deshalb unf\u00e4hig, \u00fcber ein Gesetz zu urteilen, \u00fcber Steuern, \u00fcber die Sozialistenfrage, [\u2026] weil meine Sinnlichkeit andere Wege geht als die von neunundneunzig vor mir? [\u2026] Sie ist kein m\u00f6rderischer Instinkt, kein Wahn, keine Krankheit, sie ist nichts als meine Sinnlichkeit! Wir sind nicht krank, und wir sind nicht Verbrecher \u2013 wir sind nur Variet\u00e4ten der Natur.\u201c (S. 286)<\/p><\/li><li><p>\u201eUnd doch, ich bereue nichts, keine einzige meiner Handlungen, die mich zur Strafe f\u00fchrten. [\u2026] Selbst in der einsamen Not meiner Einzelhaft habe ich nie meinen Hang verflucht, meine unbesonnenen Taten angeklagt \u2013 ich bin so \u2013 ich konnte nicht anders!\u201c (S. 304)<\/p><\/li><li><p>\u201eAber in der Liebe ist alles nur Einbildung und Anziehung! Und wenn das unsere Gesetze w\u00fc\u00dften, dann w\u00e4re Viktor Soyka heute nicht tot!\u201c (S. 327)<\/p><\/li><li><p>\u201eF\u00fcr mich ist das Gesetz nicht Gerechtigkeit. Was ist Menschenwerk? Ein Versuch! Wenn der Staat das w\u00fc\u00dfte! Aber der Staat wei\u00df nichts, er ist eine \u00f6de zermalmende Maschine [\u2026]\u201c (S. 350)<\/p><\/li><\/ul><\/div>\n            <\/div>\n                    <\/div>\n                <div class=\"theplus-accordion-item\"  role=\"tab\">\n            <div id=\"elementor-tab-title-5632\" class=\"elementor-tab-title plus-accordion-header 0 text-left \" data-tab=\"2\" aria-controls=\"elementor-tab-content-5632\">\n                                \n                <span style=\"width:100%\">Sozialer Ausschluss, Stigmatisierung durch die heteronormative Gesellschaft<\/span>                <span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-angle-down\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-angle-up\"><\/i><\/span>            <\/div>\n\n                        <div id=\"elementor-tab-content-5632\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content 0 \" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-5632\">\n                <div class=\"plus-content-editor\" ><ul><li>\u201eUeberall begegnete ihm anwachsendes Abwehren, eine mi\u00dftrauende, ewig forschende Neugierde, das peinigende Eindringen in jede Handlung. Es waren Tage voller Druck.\u201c (S. 140)<\/li><li>\u201e\u201aHomosexuell ist er,\u2018 sagte die D\u00e4nin grob heraus [\u2026] \u201aAber was soll das alles mir,\u2018 sagte sie [Barbara] endlich und sah Esther Lund mit ihren gro\u00dfen, eisigen Augen an, \u201adieser Vorwurf hat doch keinen Stachel f\u00fcr mich?\u2018 \u201aDoch,\u2018 sagte die D\u00e4nin br\u00fcsk, \u201aman wird denken, da\u00df Sie die gleiche Richtung haben \u2013 als Frau \u2013 und in diesen Verdacht kommen wir leicht \u2013 wir Frauen der Wissenschaft!\u2018\u201c (S. 147)<\/li><li><p>\u201eWie kommt die ganze Welt dazu, mich zu hassen, weil meine Regung verquer geht?\u201c (S. 187)<\/p><\/li><li><p>\u201e\u201aErlauben Sie, gn\u00e4dige Frau,\u2018 sagte Dr. Anger etwas scharf, \u201aZuchth\u00e4usler, das war er! Jetzt ist seine Schuld verb\u00fc\u00dft.\u2018 [\u2026] Aber Fr\u00e4ulein Birk sagte bestimmt: \u201aEine solche Schuld verb\u00fc\u00dft sich nicht, die bleibt \u2013 und wenn ihr auch vor dem Gesetz Gen\u00fcge geschehen ist!\u2018\u201c (S. 259)<\/p><\/li><li><p>\u201eSie sind der einzige Mensch, der mich noch seiner Beachtung wert h\u00e4lt!\u201c (S. 260)<\/p><\/li><li><p>\u201e[U]nd so stand ganz unvermittelt Lori Kurz vor ihnen, starrte sie aus gro\u00dfen, erschrockenen Augen an und floh besinnungslos zur\u00fcck, wie gehetzt. \u201aIch f\u00fcrchte, die Dame hat uns falsch verstanden,\u2018 sagte Viktor ironisch, \u201asie h\u00e4lt uns f\u00fcr Kannibalen [\u2026]\u2018\u201c (S. 289)<\/p><\/li><\/ul><\/div>\n            <\/div>\n                    <\/div>\n                <div class=\"theplus-accordion-item\"  role=\"tab\">\n            <div id=\"elementor-tab-title-5633\" class=\"elementor-tab-title plus-accordion-header 0 text-left \" data-tab=\"3\" aria-controls=\"elementor-tab-content-5633\">\n                                \n                <span style=\"width:100%\">Selbsthass, Flucht vor sich selbst<\/span>                <span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-angle-down\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-angle-up\"><\/i><\/span>            <\/div>\n\n                        <div id=\"elementor-tab-content-5633\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content 0 \" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-5633\">\n                <div class=\"plus-content-editor\" ><ul><li>\u201e[D]ies Wehren in Withalm war eine Flucht vor sich selbst. Er f\u00fcrchtete ein Reizen und Wecken seines Gef\u00fchles, er mied, was nur an Leidenschaft erinnern konnte\u201c (S. 274)<\/li><li><p>\u201e\u201aSie haben mich nicht vertrieben, gn\u00e4diges Fr\u00e4ulein,\u2018 sagte er mit rauhem, schwerm\u00fctigem Tonfall, \u201aich wollte Sie nur nicht zwingen, dieselbe Luft mit mir zu atmen [\u2026]\u2018\u201c (S. 251)<\/p><\/li><\/ul><\/div>\n            <\/div>\n                    <\/div>\n                <div class=\"theplus-accordion-item\"  role=\"tab\">\n            <div id=\"elementor-tab-title-5634\" class=\"elementor-tab-title plus-accordion-header 0 text-left \" data-tab=\"4\" aria-controls=\"elementor-tab-content-5634\">\n                                \n                <span style=\"width:100%\">\u00dcberwindung\/Durchkreuzung der Geschlechtsbinarit\u00e4t<\/span>                <span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-angle-down\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-angle-up\"><\/i><\/span>            <\/div>\n\n                        <div id=\"elementor-tab-content-5634\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content 0 \" data-tab=\"4\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-5634\">\n                <div class=\"plus-content-editor\" ><ul><li><p>\u201eVielleicht r\u00fchrt es daher, weil ich mich nie aufhalte, nachzudenken, ob ich Mann oder Weib bin. Ich bin eben ich, eine Wesenseinheit, die Form ist Nebensache!\u201c (S. 207)<\/p><\/li><li><p>\u201e\u201aAber Dr. Rabitow ist auch keine ganze Dame, sondern ein halber Herr,\u2018 sagte Maja [\u2026]\u201c (S. 363)<\/p><\/li><li><p>\u201eUnd waren sie darin nicht gleich? Da war auch sie wie er, geschlechtslos oder hermaphroditisch [\u2026]\u201c (S. 362)<\/p><\/li><li><p>\u201eIch kann so zu Ihnen sprechen, denn Sie sind vor mir nicht Mann, ich bin nicht Weib, Menschen sind wir!\u201c (S. 354)<\/p><\/li><\/ul><\/div>\n            <\/div>\n                    <\/div>\n                <div class=\"theplus-accordion-item\"  role=\"tab\">\n            <div id=\"elementor-tab-title-5635\" class=\"elementor-tab-title plus-accordion-header 0 text-left \" data-tab=\"5\" aria-controls=\"elementor-tab-content-5635\">\n                                \n                <span style=\"width:100%\">\u201aHeilung\u2018 von der Homosexualit\u00e4t durch eine \u201astarke Frau'<\/span>                <span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-angle-down\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-angle-up\"><\/i><\/span>            <\/div>\n\n                        <div id=\"elementor-tab-content-5635\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content 0 \" data-tab=\"5\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-5635\">\n                <div class=\"plus-content-editor\" ><ul><li>\u201e\u201aDann, dann liebst Du mich und bist frei von dem alten Bann! Le\u00f3n?\u2018 [\u2026] [D]a st\u00fcrzte er sich vor ihr nieder, wie ein Verurteilter vor seinem Erl\u00f6ser.\u201c (S. 377)<\/li><li><p>\u201eIch glaube, ich habe Dich gesucht mein ganzes Leben hindurch; unter den jungen M\u00e4dchen konnte ich Dich nicht finden, unter den Weibern auch nicht, da suchte ich Dich bei den M\u00e4nnern und war wieder falsch gegangen. Da kamst Du selbst!\u201c (S. 378)<\/p><\/li><li><p>\u201eSie wu\u00dfte, da\u00df vielen M\u00e4nnern die lustlose Passivit\u00e4t als der h\u00f6chste Genuss erschien, an dem der eigene Drang sich st\u00e4ndig h\u00f6her schwang. Aber Le\u00f3ns versehrte Erotik mu\u00dfte nicht weigernd, sondern l\u00f6send empfangen werden.\u201c (S. 397)<\/p><\/li><li><p>\u201e\u201aDu starkes, heiliges Weib,\u2018 sagte er sich k\u00fcssend zu ihr neigend, \u201aja, ich bin frei \u2013 und Du, wie bist Du wundervoll!\u2018\u201c (S. 413)<\/p><\/li><\/ul><\/div>\n            <\/div>\n                    <\/div>\n                <div class=\"theplus-accordion-item\"  role=\"tab\">\n            <div id=\"elementor-tab-title-5636\" class=\"elementor-tab-title plus-accordion-header 0 text-left \" data-tab=\"6\" aria-controls=\"elementor-tab-content-5636\">\n                                \n                <span style=\"width:100%\">Cross-Dressing<\/span>                <span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-angle-down\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-angle-up\"><\/i><\/span>            <\/div>\n\n                        <div id=\"elementor-tab-content-5636\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content 0 \" data-tab=\"6\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-5636\">\n                <div class=\"plus-content-editor\" ><ul><li>\u201e\u00dcberm\u00fctig fa\u00dfte er sein R\u00f6ckchen in die zierlich gespitzten Finger. \u201aBin ich nicht ein niedliches M\u00e4dchen?\u2018 rief er ausgelassen und tanzte einen grazi\u00f6sen pas seul, \u201aoh, ich werde noch arge Verw\u00fcstungen in den M\u00e4nnerherzen anrichten!\u2018\u201c (S. 124)<\/li><li>\u201eDann bei unserer Sch\u00fclervorstellung des \u201aTell\u2018 spielte ich Bertha von Bruneck und sah nach \u00fcbereinstimmender Aeu\u00dferung einfach reizend aus. Meine Conpenn\u00e4ler br\u00fcllten erst vor Lachen, dann riefen Kleid und Per\u00fccke bei Ihnen eine Art Begriffsverwirrung hervor. Sie begannen mich abzuknutschen [\u2026], ich wanderte von einem Arm in den anderen, es regnete K\u00fcsse [\u2026]\u201c (S. 232)<\/li><li><p>\u201e\u201aIch als Dietrich von Bern, bin ich nicht vollendet?\u2018 [\u2026] W\u00e4hrend ihrer Erz\u00e4hlung sah Le\u00f3n unverwandt das Bild an und begann endlich zu lachen. \u201aO, Dr. Rabitow, warum haben Sie mir nichts gesagt? So mu\u00df ich Sie sehen. Ach bitte, bitte, ziehen Sie sich an!\u2018\u201c (S. 368)<\/p><\/li><\/ul><\/div>\n            <\/div>\n                    <\/div>\n                <div class=\"theplus-accordion-item\"  role=\"tab\">\n            <div id=\"elementor-tab-title-5637\" class=\"elementor-tab-title plus-accordion-header 0 text-left \" data-tab=\"7\" aria-controls=\"elementor-tab-content-5637\">\n                                \n                <span style=\"width:100%\">Explizite Bezugnahme auf (sexual)wissenschaftliche Diskurse<\/span>                <span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-angle-down\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-angle-up\"><\/i><\/span>            <\/div>\n\n                        <div id=\"elementor-tab-content-5637\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content 0 \" data-tab=\"7\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-5637\">\n                <div class=\"plus-content-editor\" ><ul><li><p>\u201eMeist ist der Uranismus eine famili\u00e4re Anomalie [\u2026]. Sie haben das Herz nicht rechts, wie man es bei Paraesthesie h\u00e4ufig findet [\u2026]\u201c (S. 223)<\/p><\/li><li><p>\u201eFreud, der Psychoanalytiker, dem wir gerade auf sexuellem Gebiet die Zerst\u00f6rung manches Aberglaubens verdanken, erkl\u00e4rt, da\u00df wir von den biologischen Vorg\u00e4ngen, aus denen das Leben der Sexualit\u00e4t besteht, noch lange nicht genug wissen, um aus unseren vereinzelten Einsichten eine Theorie aufstellen zu k\u00f6nnen, die das Normale vom Krankhaften scharf scheidet. Die Grenzen werden immer flie\u00dfend sein. Die Variet\u00e4ten, die sexuellen Zwischenstufen [\u2026]\u201c (S. 225)<\/p><\/li><li><p>\u201e[E]s gibt keine Seele! Sie ist nach Wundt keine besondere Substanz, sondern eine Sammlung seelischer Erlebnisse [\u2026]\u201c (S. 239)<\/p><\/li><li><p>\u201eNach der neuen Theorie Sch\u00f6ners soll das Ei schon m\u00e4nnlich oder weiblich sein, aber ich neige zu der Theorie von Flie\u00df und anderen, da\u00df in jeder Zelle man das Vorhandensein weiblicher und m\u00e4nnlicher Substanz erkennen kann [\u2026]\u201c (S. 239)<\/p><\/li><li><p>\u201eNun hat Magnus Hirschfeld das Wort aufgeworfen: das Geschlecht des Menschen ruht mehr in seiner Seele, im Gehirn als im K\u00f6rper!\u201c (S. 240)<\/p><\/li><li><p>\u201eDa mu\u00df ich Dir noch ein Wort von Hirschfeld sagen! Er erkl\u00e4rt den Fetischismus nur als Teilanziehung oder partielle Anziehung, als eine stark gesteigerte Regung jenes Triebes, von dem Krafft-Ebing sagte, da\u00df [\u2026]\u201c (S. 381)<\/p><\/li><\/ul><\/div>\n            <\/div>\n                    <\/div>\n                <div class=\"theplus-accordion-item\"  role=\"tab\">\n            <div id=\"elementor-tab-title-5638\" class=\"elementor-tab-title plus-accordion-header 0 text-left \" data-tab=\"8\" aria-controls=\"elementor-tab-content-5638\">\n                                \n                <span style=\"width:100%\">Lesbisches Begehren\/Beziehungen zwischen Frauen<\/span>                <span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-angle-down\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-angle-up\"><\/i><\/span>            <\/div>\n\n                        <div id=\"elementor-tab-content-5638\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content 0 \" data-tab=\"8\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-5638\">\n                <div class=\"plus-content-editor\" ><ul><li>\u201eAn die Mauer gelehnt, standen dort zwei S\u00e4ngerinnen [\u2026]. \u201aDa, die zwei da,\u2018 erwiderte Ulbrig, \u201asie machen es doch recht sinnf\u00e4llig, ewig umschlungen und das Gek\u00fcsse und das Einander-auf-dem-Scho\u00df-sitzen!\u2018\u201c (S. 130)<\/li><li><p>\u201eBarbara [\u2026] beantwortete es durch ihr Erscheinen in der Wohnung der Malerinnen. [\u2026] [Fr\u00e4ulein Kestner] zeigte nach einem Pastell Majas, die dar\u00fcber schmollte, worauf sie mit herzlichem Lachen den blonden Kopf an ihre Brust zog und ihn k\u00fc\u00dfte. Wie ein Schatten huschte an Barbara vorbei, was man \u00fcber das Verh\u00e4ltnis der Malerinnen fl\u00fcsterte.\u201c (S. 363)<\/p><\/li><li><p>\u201eBarbaras Mund war hei\u00dfgek\u00fc\u00dft von ungez\u00e4hlten Lippen, ihr Nacken war warm von Frauenarmen.\u201c (S. 367)<\/p><\/li><\/ul><\/div>\n            <\/div>\n                    <\/div>\n                <div class=\"theplus-accordion-item\"  role=\"tab\">\n            <div id=\"elementor-tab-title-5639\" class=\"elementor-tab-title plus-accordion-header 0 text-left \" data-tab=\"9\" aria-controls=\"elementor-tab-content-5639\">\n                                \n                <span style=\"width:100%\">Suizid(versuch) queerer M\u00e4nner<\/span>                <span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-angle-down\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-angle-up\"><\/i><\/span>            <\/div>\n\n                        <div id=\"elementor-tab-content-5639\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content 0 \" data-tab=\"9\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-5639\">\n                <div class=\"plus-content-editor\" ><ul><li><p>\u201e\u201aUnd wozu sollte ich leben?\u2018 sagte er mit heiserer, gurgelnder Stimme. Da wurde sie stumm und senkte den Kopf.\u201c (S. 294)<\/p><\/li><li><p>\u201e\u201aWas willst Du tun?\u2018 rief sie laut. [\u2026] \u201aDas \u2013 das einzige, was mir zu tun bleibt!\u2018 Er nahm eine Pistole aus dem Kasten vor ihm und schleuderte sie ihr vor die F\u00fc\u00dfe.\u201c (S. 376)<\/p><\/li><\/ul><\/div>\n            <\/div>\n                    <\/div>\n        \n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6999c40 animated-slow ob-harakiri-inherit elementor-invisible ob-has-background-overlay elementor-widget elementor-widget-text-editor\" data-id=\"6999c40\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Zitiert wird die Erstausgabe von 1917.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-66a4412a e-flex e-con-boxed e-con e-parent\" data-id=\"66a4412a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eaeb911 ob-harakiri-inherit ob-has-background-overlay elementor-widget elementor-widget-heading\" data-id=\"eaeb911\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_harakiri_text_clip&quot;:&quot;none&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ansatzpunkte f\u00fcr die Lekt\u00fcre<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f5817c9 animated-slow ob-harakiri-inherit elementor-invisible ob-has-background-overlay elementor-widget elementor-widget-text-editor\" data-id=\"7f5817c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Der Titel des Romans ist Programm. Er entstammt dem Goethe-Zitat: \u201eEs ist keine Kunst, eine G\u00f6ttin zur Hexe, eine Jungfrau zur Hure zu machen: aber zur umgekehrten Operation \u2013 W\u00fcrde zu geben den Verschm\u00e4hten, w\u00fcnschenswert zu machen das Verworfene \u2013 dazu geh\u00f6rt entweder Kunst oder Charakter\u201c (S. 109). Als dieser Aphorismus dem jungen S\u00e4nger Le\u00f3n Withalm in die H\u00e4nde f\u00e4llt, macht er einen tiefen Eindruck auf ihn: \u201e[U]nd immer h\u00f6rte er die Worte: \u2026 \u201aW\u00fcrde zu geben den Verschm\u00e4hten \u2013 w\u00fcnschenswert zu machen das Verworfene\u2026\u2018 Es war endlich wie ein leise fl\u00fcsterndes Echo seines Herzschlages [\u2026]\u201c (S. 109).<\/p><p>\u00a0<\/p><p>Wie ein Echo zieht sich das Zitat fortan auch durch den Roman. Einer der Verschm\u00e4hten, um die es da geht, hei\u00dft Viktor Soyka. Nach f\u00fcnfj\u00e4hriger Inhaftierung wegen dem \u00a7 175 wird der ehemalige S\u00e4nger von Le\u00f3n aufgenommen. Viktor ist ein innerlich gebrochener Mann, der sich schlie\u00dflich das Leben nimmt, jedoch bis zuletzt unbeirrt auf seiner W\u00fcrde beharrt: \u201eWas geht mein Sexus den Staat an? Gef\u00e4hrdet er ihn? Bedroht er ihn? [\u2026] [B]in ich deshalb unf\u00e4hig, \u00fcber ein Gesetz zu urteilen, \u00fcber Steuern, \u00fcber die Sozialistenfrage, [\u2026] weil meine Sinnlichkeit andere Wege geht als die von neunundneunzig vor mir? [\u2026] Sie ist kein m\u00f6rderischer Instinkt, kein Wahn, keine Krankheit, sie ist nichts als meine Sinnlichkeit! Wir sind nicht krank, und wir sind nicht Verbrecher \u2013 wir sind nur Variet\u00e4ten der Natur\u201c (S. 286).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d6d831d ob-has-background-overlay elementor-widget elementor-widget-tp-accordion\" data-id=\"d6d831d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;}\" data-widget_type=\"tp-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"theplus-accordion-wrapper elementor-accordion   \"\n    id=\"accordion6a0425f95cf63\" data-accordion-id=\"accordion6a0425f95cf63\"\n    data-connection=\"\"\n    data-accordion-type=\"accordion\"\n    data-heightlight-text       role=\"tablist\" >\n\n            <div class=\"theplus-accordion-item\"  role=\"tab\">\n            <div id=\"elementor-tab-title-2251\" class=\"elementor-tab-title plus-accordion-header 0 text-left \" data-tab=\"1\" aria-controls=\"elementor-tab-content-2251\">\n                                <span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-angle-down\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-angle-up\"><\/i><\/span>\n                <span style=\"width:100%\">weiterlesen<\/span>                            <\/div>\n\n                        <div id=\"elementor-tab-content-2251\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content 0 \" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-2251\">\n                <div class=\"plus-content-editor\" ><p>Der gesamte Roman ist von queeren Figuren und Konstellationen durchzogen. Erz\u00e4hlt wird etwa von Oskar J\u00e4hnisch, der im Frauenkost\u00fcm von Maskenball zu Maskenball zieht, um dort \u201earge Verw\u00fcstung in den M\u00e4nnerherzen an[zu]richten\u201c (S. 124). Der Bildhauer Heinz Mylius f\u00fchrt nach au\u00dfen hin eine b\u00fcrgerliche Ehe, doch wird ihm \u201edie Beziehung [\u2026] nur m\u00f6glich, wenn er sich M\u00e4nner vorstellt\u201c (S. 170). Die Malerin Fr\u00e4ulein Kestner lebt harmonisch mit \u201eihrer unzertrennlichen Gef\u00e4hrtin Maja von Belling\u201c (S. 87) zusammen, und die D\u00e4nin Esther Lund, die Frauenrechtler:innen wie Anita Augspurg und Ruth Br\u00e9 zitiert, \u201ewar v\u00f6llig zum Manne geworden [\u2026]\u201c (S. 123). Als die Protagonistin Barbara in der Theaterauff\u00fchrung eines Damenklub als Dietrich von Bern auftritt, ist ihr Mund bald \u201ehei\u00dfgek\u00fc\u00dft von ungez\u00e4hlten Lippen, ihr Nacken war warm von Frauenarmen\u201c (S. 367).<\/p><p>\u00a0<\/p><p>Eine Besonderheit des Romans liegt darin, dass er sein Hauptthema \u2013 sexuelle und geschlechtliche \u201aVariet\u00e4ten\u2018 sowie Kritik an heteronormativer Moral \u2013 auf unterschiedlichen diskursiven Ebenen entfaltet. W\u00e4hrend der ehemalige H\u00e4ftling Viktor mit flammenden politischen Reden gegen den \u00a7 175 Stellung bezieht, bringt die \u00c4rztin Dr. Barbara Rabitow zeitgen\u00f6ssische sexualwissenschaftliche Diskurse ein. Sie verweist auf zentrale Figuren wie Magnus Hirschfeld, Richard von Krafft-Ebing, Sigmund Freud, Wilhelm Flie\u00df und Wilhelm Wundt und referiert ausf\u00fchrlich \u00fcber Konzepte wie den \u201eUranismus\u201c (S. 223) oder die \u201esexuellen Zwischenstufen\u201c (S. 225). Barbara ist selbst geschlechtlich uneindeutig markiert: Ihre kompromisslose Hingabe zur Wissenschaft und ihr dominantes Auftreten f\u00fchren dazu, dass sie von ihrer Umwelt als \u201eM\u00e4nnin\u201c (S. 277) wahrgenommen wird. Im Verh\u00e4ltnis zu den queeren Figuren Viktor und Le\u00f3n \u00fcbernimmt sie eine freundschaftliche, aufkl\u00e4rerische und zugleich therapeutische Funktion.<\/p><p>\u00a0<\/p><p>Der Roman macht zudem auf differenzierte Weise auf gesellschaftliche Ausschlussmechanismen aufmerksam. Die soziale Isolation, in die Le\u00f3n infolge des Ger\u00fcchts \u00fcber seine angebliche Homosexualit\u00e4t ger\u00e4t, speist sich aus einer weitverbreiteten Angst vor Abwertung durch Assoziation: Der Umgang mit dem \u201aPerversen\u2018 gilt als rufsch\u00e4digend, weshalb sich sein Umfeld zunehmend von ihm distanziert. Zugleich geraten im Kontakt mit queeren Figuren vermeintliche Identit\u00e4tsgewissheiten rasch ins Wanken. So f\u00fchren Oskar J\u00e4hnischs Auftritte als Frau im Publikum zu einer \u201ev\u00f6llige[n] Begriffsverwirrung\u201c (S. 122), und als die Ger\u00fcchte \u00fcber Le\u00f3n zu kursieren beginnen, stellt sein Kollege Ernst H\u00f6ber schockiert fest, dass \u201e[e]r, der Vollblutmann, [\u2026] mit dem bildh\u00fcbschen, scheuen, empfindlichen Withalm manchmal umgegangen sei wie mit einem M\u00e4dchen\u201c (S. 171). Er schlie\u00dft sich rasch dem Urteil seiner Frau an, als diese fordert: \u201e[D]ieser Withalm kommt mir nicht mehr \u00fcber die Schwelle [\u2026]. [M]it zweifelhaften Elementen will ich mich nicht beflecken!\u201c (S. 172)<\/p><p>\u00a0<\/p><p>Die Wertungen und Modelle des Romans in Bezug auf Geschlecht und Sexualit\u00e4t entziehen sich einer einfachen Einordnung. Zwar formuliert der Text ein deutliches Pl\u00e4doyer gegen den \u00a7 175, doch finden sich auch abwertende Tendenzen, so zum Beispiel in Barbaras herablassender Bemerkung \u00fcber den transweiblichen Oskar J\u00e4hnisch: \u201e[J]etzt sind Sie ein \u00e4sthetisches Faultierchen geworden, ein Luxuspfl\u00e4nzchen, ein H\u00e4tschelchen!\u201c (S. 344). Auff\u00e4llig ist zudem die wiederkehrende Unterscheidung zwischen Veranlagung und Handlung. So betont Le\u00f3n bei seinem Outing gegen\u00fcber Barbara: \u201e[I]ch geh\u00f6re absolut nicht zu den sogenannten homosexuellen Kreisen, ich habe mir in keiner Weise einen Vorwurf zu machen\u201c (S. 151), w\u00e4hrend Viktor eine gegenteilige Haltung einnimmt: \u201e[I]ch bereue nichts, keine einzige meiner Handlungen [\u2026]\u201c (S. 304). Auch Barbara selbst erscheint ambivalent: Einerseits zeigt sie sich aufgeschlossen, andererseits versp\u00fcrt sie unwillk\u00fcrlich einen \u201eschleichende[n] Ekel\u201c (S. 169) beim Gedanken an schwule Sexualit\u00e4t.<\/p><p>\u00a0<\/p><p>Im Zeichen solcher Ambivalenzen steht schlie\u00dflich auch das Ende des Romans, das mit der relativ unerwarteten Verlobung zwischen Le\u00f3n und Barbara eine weitere Wendung erf\u00e4hrt. Diese Verbindung wird als \u201eR\u00fcckwandlung\u201c (S. 399) Le\u00f3ns und als Heilung seiner \u201eversehrte[n] Erotik\u201c (S. 397) inszeniert. Parallel dazu vollzieht sich Barbaras freiwillige Frauwerdung: \u201eIch will nicht Kamerad sein, sondern sein Weib [\u2026]\u201c (S. 411). Diese Entscheidung bleibt jedoch nicht unhinterfragt, sondern sie wird aus feministischer Perspektive explizit kritisiert: \u201eEine Frau, die Selbstachtung besitzt, kann eine gesetzliche Ehe nicht eingehen [\u2026]\u201c (S. 405). Gleichwohl handelt es sich bis zuletzt nicht um eine klassisch heteronormative Beziehung. \u00a0Zum einen begehrt Le\u00f3n ausdr\u00fccklich \u201enicht das M\u00e4dchen, sondern den Mann in Dir\u201c (S. 377); zum anderen betonen beide die Vorrangstellung der Freundschaft und einer \u00fcber Geschlechtergrenzen hinausgehenden menschlichen Verbindung: \u201eIch m\u00fc\u00dfte dich lieben, Mann oder Weib!\u201c (S. 288). Das Ende l\u00e4sst sich somit einerseits als normalisierende Einhegung, andererseits auch als queere Umdeutung der Ehe als \u201efrei gewollte Gemeinschaft zweier Menschen, einerlei welchen Geschlechts\u201c (S. 306) lesen.<\/p><p>\u00a0<\/p><p>Der Roman zeugt von einer bemerkenswert informierten und originellen Auseinandersetzung mit den heteronormativit\u00e4tskritischen Diskursen seiner Zeit. Er verdient vertiefte Untersuchungen.<\/p><\/div>\n            <\/div>\n                    <\/div>\n        \n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5e21f6d0 e-flex e-con-boxed e-con e-parent\" data-id=\"5e21f6d0\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-26c48b4d ob-harakiri-inherit ob-has-background-overlay elementor-widget elementor-widget-heading\" data-id=\"26c48b4d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_harakiri_text_clip&quot;:&quot;none&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Bibliografische Angaben <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-335d4574 e-flex e-con-boxed e-con e-child\" data-id=\"335d4574\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-11292053 e-flex e-con-boxed e-con e-child\" data-id=\"11292053\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-66447674 e-grid e-con-boxed e-con e-child\" data-id=\"66447674\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2f945879 animated-slow ob-harakiri-inherit elementor-invisible ob-has-background-overlay elementor-widget elementor-widget-text-editor\" data-id=\"2f945879\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Erstausgabe<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42f03dc5 animated-slow ob-harakiri-inherit elementor-invisible ob-has-background-overlay elementor-widget elementor-widget-text-editor\" data-id=\"42f03dc5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Marfa von Sacher-Masoch: <em>\u201eW\u00fcrde zu geben den Verschm\u00e4hten\u2026\u201c<\/em>. Leipzig: Dr. Sally Rabinowitz Verlag, 1917.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-460e4152 e-flex e-con-boxed e-con e-child\" data-id=\"460e4152\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7f76f530 e-grid e-con-boxed e-con e-child\" data-id=\"7f76f530\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-145fa933 animated-slow ob-harakiri-inherit elementor-invisible ob-has-background-overlay elementor-widget elementor-widget-text-editor\" data-id=\"145fa933\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Neudrucke<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4370cc54 animated-slow ob-harakiri-inherit elementor-invisible ob-has-background-overlay elementor-widget elementor-widget-text-editor\" data-id=\"4370cc54\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die dritte und vierte Auflage erschienen 1925 in Leipzig beim Dr. Sally Rabinowitz Verlag.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-25a62750 e-flex e-con-boxed e-con e-child\" data-id=\"25a62750\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1e36bfaf e-grid e-con-boxed e-con e-child\" data-id=\"1e36bfaf\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-67afe10f animated-slow ob-harakiri-inherit elementor-invisible ob-has-background-overlay elementor-widget elementor-widget-text-editor\" data-id=\"67afe10f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Kritische Ausgabe<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ee3799b animated-slow ob-harakiri-inherit elementor-invisible ob-has-background-overlay elementor-widget elementor-widget-text-editor\" data-id=\"1ee3799b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Keine.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5eefe8de e-flex e-con-boxed e-con e-child\" data-id=\"5eefe8de\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5f8236c5 e-grid e-con-boxed e-con e-child\" data-id=\"5f8236c5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5f74a170 animated-slow ob-harakiri-inherit elementor-invisible ob-has-background-overlay elementor-widget elementor-widget-text-editor\" data-id=\"5f74a170\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00dcbersetzung<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-378c8aa1 animated-slow ob-harakiri-inherit elementor-invisible ob-has-background-overlay elementor-widget elementor-widget-text-editor\" data-id=\"378c8aa1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Keine.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-31395159 e-flex e-con-boxed e-con e-child\" data-id=\"31395159\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-339cbf7f e-grid e-con-boxed e-con e-child\" data-id=\"339cbf7f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f5045da animated-slow ob-harakiri-inherit elementor-invisible ob-has-background-overlay elementor-widget elementor-widget-text-editor\" data-id=\"f5045da\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Literaturrecherche<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7842af7f animated-slow ob-harakiri-inherit elementor-invisible ob-has-background-overlay elementor-widget elementor-widget-text-editor\" data-id=\"7842af7f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>BDSL-online am 20.05.25, weitere Recherchen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-67f4c524 ob-has-background-overlay elementor-widget elementor-widget-tp-accordion\" data-id=\"67f4c524\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;}\" data-widget_type=\"tp-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"theplus-accordion-wrapper elementor-accordion   \"\n    id=\"accordion6a0425f960d22\" data-accordion-id=\"accordion6a0425f960d22\"\n    data-connection=\"\"\n    data-accordion-type=\"accordion\"\n    data-heightlight-text       role=\"tablist\" >\n\n            <div class=\"theplus-accordion-item\"  role=\"tab\">\n            <div id=\"elementor-tab-title-1741\" class=\"elementor-tab-title plus-accordion-header 0 text-left \" data-tab=\"1\" aria-controls=\"elementor-tab-content-1741\">\n                                <span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\"><i class=\"elementor-accordion-icon-closed fa fa-angle-down\"><\/i><i class=\"elementor-accordion-icon-opened fa fa-angle-up\"><\/i><\/span>\n                <span style=\"width:100%\">Bibliografie<\/span>                            <\/div>\n\n                        <div id=\"elementor-tab-content-1741\" class=\"elementor-tab-content elementor-clearfix plus-accordion-content 0 \" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1741\">\n                <div class=\"plus-content-editor\" ><p>Constanze Mudra: <em>Marfa von Sacher-Masoch: \u201eW\u00fcrde zu geben den Verschm\u00e4hten\u2026\u201c. Ein queerer Klassiker aus dem Jahre 1925. <\/em>Blogeintrag auf der Webseite der Louise-Otto-Peters-Gesellschaft e.V. vom 07.09.2021 [<a href=\"https:\/\/www.louiseottopeters-gesellschaft.de\/blog\/marfa-von-sacher-masoch-wuerde-zu-geben-den-verschmaehten-ein-queerer-klassiker-aus-dem-jahre-1925\">Link<\/a>].<\/p><p>\u00a0<\/p><p>Biografisches zu Marfa von Sacher-Masoch findet sich in:<\/p><p>\u00a0<\/p><p>M. Coray: Die drei Kinder im Herrengarten. Edition eines Romans von Marfa von Sacher-Masoch (vrh. Saternus). Hrsg. v. Marion Kobelt-Groch unter Mitwirkung von Astrid Schlachta. Kiel: Solivagus-Verlag, 2022.<\/p><\/div>\n            <\/div>\n                    <\/div>\n        \n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d3cba35 e-flex e-con-boxed e-con e-parent\" data-id=\"d3cba35\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;_ob_use_container_extras&quot;:&quot;no&quot;,&quot;_ob_column_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_glider_is_slider&quot;:&quot;no&quot;,&quot;_ob_column_has_pseudo&quot;:&quot;no&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-deaa7ab animated-slow ob-harakiri-inherit elementor-invisible ob-has-background-overlay elementor-widget elementor-widget-text-editor\" data-id=\"deaa7ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_ob_use_harakiri&quot;:&quot;yes&quot;,&quot;_ob_harakiri_writing_mode&quot;:&quot;inherit&quot;,&quot;_ob_perspektive_use&quot;:&quot;no&quot;,&quot;_ob_poopart_use&quot;:&quot;yes&quot;,&quot;_ob_shadough_use&quot;:&quot;no&quot;,&quot;_ob_allow_hoveranimator&quot;:&quot;no&quot;,&quot;_ob_widget_stalker_use&quot;:&quot;no&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Das Literaturportr\u00e4t wurde von Paola Rigi-Luperti, studentische Mitarbeiterin der Forschungsstelle Kulturgeschichte der Sexualit\u00e4t, erstellt.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Sacher-Masoch, Marfa von: &#8222;W\u00fcrde zu geben den Verschm\u00e4hten&#8230;&#8220; (1917) Stammdaten Autor*in Marfa von Sacher-Masoch (vrh. Saternus) Vollst\u00e4ndiger Titel \u201eW\u00fcrde zu geben den Verschm\u00e4hten\u2026\u201c Pseudonym M. Coray Ersterscheinungsjahr 1917 (dritte und vierte Auflage im Jahr 1925) Epoche Deutsches Kaiserreich Fassung \u00a7175 1872-1935 Gattung Roman Biografisches Abb 1. Deckblatt der Erstausgabe des Romans von 1917. Marfa von [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[15],"class_list":["post-4418","post","type-post","status-publish","format-standard","hentry","category-weimarer-republik","tag-literaturportraets"],"_links":{"self":[{"href":"https:\/\/www2.cms.hu-berlin.de\/queer-reading\/wp-json\/wp\/v2\/posts\/4418","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www2.cms.hu-berlin.de\/queer-reading\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www2.cms.hu-berlin.de\/queer-reading\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www2.cms.hu-berlin.de\/queer-reading\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www2.cms.hu-berlin.de\/queer-reading\/wp-json\/wp\/v2\/comments?post=4418"}],"version-history":[{"count":48,"href":"https:\/\/www2.cms.hu-berlin.de\/queer-reading\/wp-json\/wp\/v2\/posts\/4418\/revisions"}],"predecessor-version":[{"id":4474,"href":"https:\/\/www2.cms.hu-berlin.de\/queer-reading\/wp-json\/wp\/v2\/posts\/4418\/revisions\/4474"}],"wp:attachment":[{"href":"https:\/\/www2.cms.hu-berlin.de\/queer-reading\/wp-json\/wp\/v2\/media?parent=4418"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www2.cms.hu-berlin.de\/queer-reading\/wp-json\/wp\/v2\/categories?post=4418"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www2.cms.hu-berlin.de\/queer-reading\/wp-json\/wp\/v2\/tags?post=4418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}